{"id":109212,"date":"2021-07-14T16:02:26","date_gmt":"2021-07-14T15:02:26","guid":{"rendered":"https:\/\/wowtea.eu\/pt\/?post_type=product&#038;p=109212"},"modified":"2026-06-30T11:14:05","modified_gmt":"2026-06-30T10:14:05","slug":"tea-thermos-pink","status":"publish","type":"product","link":"https:\/\/wowtea.eu\/pt\/product\/tea-thermos-pink\/","title":{"rendered":"Termo de infus\u00e3o de ch\u00e1 \u2013 Rosa"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"109212\" class=\"elementor elementor-109212\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-064321b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"064321b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a85ec2f\" data-id=\"a85ec2f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b90874 elementor-widget elementor-widget-template\" data-id=\"0b90874\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"172161\" class=\"elementor elementor-172161\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e86ef70 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e86ef70\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3698d99\" data-id=\"3698d99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0762bdb elementor-widget elementor-widget-free_plans\" data-id=\"0762bdb\" data-element_type=\"widget\" data-widget_type=\"free_plans.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n               <div class=\"row free_plan_box_wrapper\">\n                           <div class=\"free_plan_box\">\n                  <div class=\"img_wrap\">\n                     <figure>\n                                                   <img src=\"https:\/\/wowtea.eu\/pt\/files\/2026\/12\/plans-and-program-20256-cover-index-food-plan.webp\" alt=\"&lt;span&gt; + Gr\u00e1tis &lt;\/span&gt; Modo Comida\" title=\"|\">\n                                             <\/figure>\n                  <\/div>\n                  <div class=\"content\">\n                     <h4 class=\"icon_title\"><span> + Gr\u00e1tis <\/span> Modo Comida <small>em todas as encomendas!<\/small><\/h4>\n                  <\/div>\n               <\/div>\n                           <div class=\"free_plan_box\">\n                  <div class=\"img_wrap\">\n                     <figure>\n                                                   <img src=\"https:\/\/wowtea.eu\/pt\/files\/2026\/12\/plans-and-program-20256-cover-index-workout-program.webp\" alt=\"&lt;span&gt; + Gr\u00e1tis &lt;\/span&gt;Plano de exerc\u00edcios\" title=\"|\">\n                                             <\/figure>\n                  <\/div>\n                  <div class=\"content\">\n                     <h4 class=\"icon_title\"><span> + Gr\u00e1tis <\/span>Plano de exerc\u00edcios <small>em todas as encomendas acima de \u20ac40<\/small><\/h4>\n                  <\/div>\n               <\/div>\n                           <div class=\"free_plan_box\">\n                  <div class=\"img_wrap\">\n                     <figure>\n                                                   <img src=\"https:\/\/wowtea.eu\/pt\/files\/2026\/12\/plans-and-program-20256-cover-index-yoga.webp\" alt=\"&lt;span&gt; + Gr\u00e1tis &lt;\/span&gt; Plano de ioga\" title=\"|\">\n                                             <\/figure>\n                  <\/div>\n                  <div class=\"content\">\n                     <h4 class=\"icon_title\"><span> + Gr\u00e1tis <\/span> Plano de ioga <small>com todas as ordens de ch\u00e1 Wellness!<\/small><\/h4>\n                  <\/div>\n               <\/div>\n                     <\/div>\n         \n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a47dc5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a47dc5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c6ce8e0\" data-id=\"c6ce8e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2ad047 elementor-widget elementor-widget-image\" data-id=\"b2ad047\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/07\/1-eco.svg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a96d39b\" data-id=\"a96d39b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7ef4db elementor-widget elementor-widget-image\" data-id=\"c7ef4db\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/07\/2-12-24.svg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6d78420\" data-id=\"6d78420\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76e595b elementor-widget elementor-widget-image\" data-id=\"76e595b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/07\/3-Badges-Recovered_infusion.svg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c0679c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7c0679c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-609c8be\" data-id=\"609c8be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ecba86 elementor-widget elementor-widget-custom_title\" data-id=\"2ecba86\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>Criando a garrafa t\u00e9rmica com infusor WOW TEA<\/span> <small style=\"order: \"><br><span style=\"color:#d60057\">Desfrute do seu ch\u00e1 com estilo!<\/span><\/small><\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd84b4b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd84b4b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08ed84f\" data-id=\"08ed84f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aec81f elementor-widget elementor-widget-text-editor\" data-id=\"4aec81f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"font-size: 15px;font-weight: 500;padding: 15px;background-color: #fbe5ee;border-radius: 15px;color: black\">O nosso superpoder \u00e9 criar <strong style=\"color: #d60057\">misturas de ervas com uma a\u00e7\u00e3o natural para melhorar a forma e a sa\u00fade. <\/strong>Para esse prop\u00f3sito, a natureza d\u00e1-nos a suas melhores ervas, ent\u00e3o achamos que \u00e9 justo retribu\u00ed-la! \u00c9 por isso que, al\u00e9m de fazer misturas de ch\u00e1 para tonificar o corpo de uma forma saud\u00e1vel, <strong style=\"color: #d60057\">tamb\u00e9m criamos garrafas e garrafas t\u00e9rmicas reutiliz\u00e1veis \u200b\u200be ecologicas!<\/strong><\/p><p style=\"font-size: 15px;font-weight: 400;text-align: start\">Constru\u00edda com <strong>a\u00e7o inoxid\u00e1vel de alta qualidade,<\/strong> a garrafa t\u00e9rmica com infusor WOW TEA foi projetada para durar centenas de utiliza\u00e7\u00f5es, ajudando assim a reduzir o desperd\u00edcio de pl\u00e1stico e transformando a sua ingest\u00e3o de ch\u00e1 numa cerim\u00f4nia emocionante.<\/p><p style=\"font-size: 15px;font-weight: 400;text-align: start\">Al\u00e9m disso, a filtra\u00e7\u00e3o avan\u00e7ada permite <strong>extrair a maior quantidade de ingredientes \u200b\u200bdo seu ch\u00e1<\/strong>, desfrutando do efeito mais forte das ervas!<\/p><p style=\"font-size: 15px;font-weight: 400;text-align: start\">O design dur\u00e1vel, \u00e0 prova de vazamentos e resistente a arranh\u00f5es suportar\u00e1 qualquer coisa, que a leve para o escrit\u00f3rio, gin\u00e1sio ou ao ar livre. Devido \u00e0s paredes duplas com isolamento t\u00e9rmico, a garrafa t\u00e9rmica <strong>mant\u00e9m o seu ch\u00e1 quente por 12h e frio por 24h!\u00a0<\/strong><\/p><p>Por \u00faltimo, pode escolher entre 3 cores espetaculares &#8211; <strong>rosa atrevido, preto elegante ou laranja extravagante<\/strong> &#8211; deixando a impress\u00e3o certa em qualquer lugar que v\u00e1! E tamb\u00e9m complementando a sua rotina ecol\u00f3gica com um h\u00e1bito sustent\u00e1vel que \u00e9 \u00f3timo para si e para o planeta!<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5e67e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5e67e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae0a58\" data-id=\"8ae0a58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8db830 elementor-widget elementor-widget-image\" data-id=\"b8db830\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/07\/keep-it-fresh-keep-it-wow-Pink-1.svg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5750729 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"5750729\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb7e0e9\" data-id=\"eb7e0e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e9d970 elementor-widget elementor-widget-image\" data-id=\"3e9d970\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"347\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-1024x347.jpg\" class=\"attachment-large size-large wp-image-104979\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-1024x347.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-300x102.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-768x260.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-1536x520.jpg 1536w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D-600x203.jpg 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-D.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-efecce7\" data-id=\"efecce7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92ca5c8 elementor-widget elementor-widget-image\" data-id=\"92ca5c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"320\" height=\"216\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/Spring-reborn-Option-box-1.jpg\" class=\"attachment-large size-large wp-image-104982\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/Spring-reborn-Option-box-1.jpg 320w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/Spring-reborn-Option-box-1-300x203.jpg 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3008269\" data-id=\"3008269\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a128940 elementor-widget elementor-widget-image\" data-id=\"a128940\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"400\" height=\"435\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-M.jpg\" class=\"attachment-large size-large wp-image-104983\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-M.jpg 400w, https:\/\/wowtea.eu\/pt\/files\/2021\/06\/easy-to-banner-black-bottle-M-276x300.jpg 276w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee4ce24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee4ce24\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecf68d7\" data-id=\"ecf68d7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbaf097 elementor-widget elementor-widget-heading\" data-id=\"bbaf097\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"color: #000;text-align: center;margin: 0;padding:0\"><\/p><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a99945f elementor-widget elementor-widget-template\" data-id=\"a99945f\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"141571\" class=\"elementor elementor-141571\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d529999 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d529999\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48ca8cd\" data-id=\"48ca8cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b5518f elementor-widget elementor-widget-shortcode\" data-id=\"3b5518f\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><p style='color: #000;text-align: center;margin: 0;padding:0;font-size: 25px;font-weight: bold;font-family: 'Gothic', sans-serif;'>Os mais vendidos<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-266b9d7 elementor-widget elementor-widget-html\" data-id=\"266b9d7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"atp-slider\" data-products=\"154947,191500|191501,167971,72426|72438,187321,115544,189261|189264,72456,169546,155013|155014\">\n\t<div class=\"atp-slider-loading\"><div class=\"atp-slider-loading-animation\"><\/div><\/div> \n\t<div class=\"atp-slider-item\">\n        <span class=\"on_sale\">\n            <span class=\"atp-slider-discount-1\">Poupe <span class=\"price_savings_percentage\">20<\/span>%<\/span>\n            <span class=\"atp-slider-discount-2\">Poupe <span class=\"price_savings_percentage\">30<\/span>%<\/span>\n        <\/span>\n        <div class=\"atp-slider-img\">\n            <img loading=\"lazy\" \/>\n            <p class=\"atp-slider-delivery\"><span class='atp-slider-delivery-holder'><span class='atp-slider-delivery-text'><\/span><span class='atp-slider-delivery-icon'> \u26df<\/span><\/span><\/p>\n        <\/div>\n        <h4><a href=\"#\" class=\"name\"><\/a><\/h4>\n        <p><span class=\"price_html sale_price\"><\/span> <\/p>\n        <p class=\"price-savings\">poupa <span class=\"price-savings-nominal\"> <\/span><\/p>\n       <a href=\"#\" class=\"atp-slider-button add_to_cart_button ajax_add_to_cart\" data-quantity=\"1\" data-product_id=\"72456\" data-product_sku=\"WOW-P-DTXSF\" rel=\"nofollow\">Adicionar<\/a>\n    <\/div>\n\t\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d97594a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d97594a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef9d3f5\" data-id=\"ef9d3f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29d1da3 elementor-widget elementor-widget-custom_title\" data-id=\"29d1da3\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>Materiais de alta qualidade e <br>design luxuoso<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb53121 elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"cb53121\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"667\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-1024x667.jpg\" class=\"attachment-large size-large wp-image-137739\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-1024x667.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-300x195.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-768x500.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-100x65.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1-600x391.jpg 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-PINK-D-PT-1.jpg 1152w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f404e3 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"2f404e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19a1699\" data-id=\"19a1699\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a286c9 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"7a286c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"360\" height=\"457\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-pink-M-PT-1.jpg\" class=\"attachment-large size-large wp-image-137740\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-pink-M-PT-1.jpg 360w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-pink-M-PT-1-236x300.jpg 236w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-parts-pink-M-PT-1-79x100.jpg 79w\" sizes=\"(max-width: 360px) 100vw, 360px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91c855b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91c855b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7a10ca\" data-id=\"f7a10ca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f0ddaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f0ddaf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7f1f012\" data-id=\"7f1f012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1136aae elementor-widget elementor-widget-text-editor\" data-id=\"1136aae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>A escolha de garrafas t\u00e9rmicas reutiliz\u00e1veis de a\u00e7o inoxid\u00e1vel em vez de garrafas pl\u00e1sticas descart\u00e1veis \u00e9 um pequeno passo de grande import\u00e2ncia &#8211; <strong style=\"color: #000\">se quisermos ajudar a manter o ambiente limpo!<\/strong> Al\u00e9m disso, a nossa garrafa t\u00e9rmica guarda a frescura do seu WOW TEA durante todo o dia, para que possa sabore\u00e1-lo em qualquer lugar, a qualquer hora! <strong style=\"color: #d60057\">Mantenha-o quente por 12h e frio &#8211; por 24h!<\/strong><\/p><p>Por \u00faltimo, ao preparar o seu ch\u00e1 na nossa garrafa t\u00e9rmica WOW TEA, extrai o m\u00e1ximo de benef\u00edcios das ervas de dentro, <strong style=\"color: #d60057\">obtendo o efeito mais forte e o sabor mais rico. <\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b53d92 elementor-section-full_width elementor-hidden-tablet elementor-hidden-phone elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"9b53d92\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e01048c\" data-id=\"e01048c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20261cb elementor-widget elementor-widget-spacer\" data-id=\"20261cb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7732d36 elementor-widget elementor-widget-heading\" data-id=\"7732d36\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b style=\"font-weight:600\">BOAS vibra\u00e7\u00f5es <\/b><br>\na cada GOLE<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10dbda5 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"10dbda5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aea2b3e\" data-id=\"aea2b3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e35e5ab elementor-widget elementor-widget-spacer\" data-id=\"e35e5ab\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d293733 elementor-widget elementor-widget-spacer\" data-id=\"d293733\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27291a2 elementor-widget elementor-widget-heading\" data-id=\"27291a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b style=\"font-weight:600\">BOAS vibra\u00e7\u00f5es <\/b><br>\na cada GOLE<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4074898 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4074898\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3d2128\" data-id=\"a3d2128\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6558af0 elementor-widget elementor-widget-custom_title\" data-id=\"6558af0\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>Design da pr\u00f3xima gera\u00e7\u00e3o<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a606e elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"b7a606e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1920\" height=\"744\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt.jpg\" class=\"attachment-full size-full wp-image-109267\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt.jpg 1920w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt-300x116.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt-1024x397.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt-768x298.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt-1536x595.jpg 1536w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-D-pt-600x233.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a518b2e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"a518b2e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"460\" height=\"750\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-M-pt.jpg\" class=\"attachment-large size-large wp-image-109266\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-M-pt.jpg 460w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Thermos-layers-pink-M-pt-184x300.jpg 184w\" sizes=\"(max-width: 460px) 100vw, 460px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d395296 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d395296\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f77d8bc\" data-id=\"f77d8bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7125f8a elementor-widget elementor-widget-custom_title\" data-id=\"7125f8a\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>Beber ch\u00e1 com estilo!<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a18248 elementor-hidden-phone elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0a18248\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b591ed0\" data-id=\"b591ed0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb31bc pp-hotspot-img-align-center elementor-widget elementor-widget-pp-image-hotspots\" data-id=\"5eb31bc\" data-element_type=\"widget\" data-settings=\"{&quot;tooltip_trigger&quot;:&quot;hover&quot;,&quot;tooltip_arrow&quot;:&quot;yes&quot;}\" data-widget_type=\"pp-image-hotspots.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-image-hotspots\">\n\t\t\t<div class=\"pp-hot-spot-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-398d7d0 pp-hot-spot-tooptip\" data-tooltip=\"Design requintado e confort\u00e1vel\" data-tooltip-position=\"tt-left\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-5cecaef pp-hot-spot-tooptip\" data-tooltip=\"Super f\u00e1cil de usar e limpar\" data-tooltip-position=\"tt-left\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-d264a34 pp-hot-spot-tooptip\" data-tooltip=\"Temperatura perfeita do ch\u00e1 o dia todo\" data-tooltip-position=\"tt-left\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t<img width=\"1920\" height=\"650\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d.jpg\" class=\"attachment-full size-full wp-image-137743\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d.jpg 1920w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-300x102.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-1024x347.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-768x260.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-1536x520.jpg 1536w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-100x34.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-d-600x203.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"|\">\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd754a9 elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"bd754a9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecf0c1f\" data-id=\"ecf0c1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c18ef72 pp-hotspot-img-align-center elementor-widget elementor-widget-pp-image-hotspots\" data-id=\"c18ef72\" data-element_type=\"widget\" data-settings=\"{&quot;tooltip_trigger&quot;:&quot;hover&quot;,&quot;tooltip_arrow&quot;:&quot;yes&quot;}\" data-widget_type=\"pp-image-hotspots.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-image-hotspots\">\n\t\t\t<div class=\"pp-hot-spot-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-398d7d0 pp-hot-spot-tooptip\" data-tooltip=\"Design requintado e confort\u00e1vel\" data-tooltip-position=\"tt-left\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-5cecaef pp-hot-spot-tooptip\" data-tooltip=\"Super f\u00e1cil de usar e limpar\" data-tooltip-position=\"tt-bottom\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-hot-spot-wrap elementor-repeater-item-d264a34 pp-hot-spot-tooptip\" data-tooltip=\"Temperatura perfeita do ch\u00e1 o dia todo\" data-tooltip-position=\"tt-bottom\" data-tooltip-size=\"tiny\" data-tooltip-width=\"140\">\n\t\t\t\t\t\t<span class=\"pp-hot-spot-inner hotspot-animation\">\n\t\t\t\t\t\t\t<span class=\"pp-hotspot-icon-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t<img width=\"460\" height=\"600\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-m.jpg\" class=\"attachment-full size-full wp-image-137744\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-m.jpg 460w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-m-230x300.jpg 230w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Drinking-in-style-pink-m-77x100.jpg 77w\" sizes=\"(max-width: 460px) 100vw, 460px\" title=\"|\">\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4564f9b elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4564f9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e433584\" data-id=\"e433584\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94e5826 elementor-widget elementor-widget-accordion\" data-id=\"94e5826\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1561\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1561\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Quais s\u00e3o os benef\u00edcios para a sa\u00fade de usar uma garrafa t\u00e9rmica para beber ch\u00e1?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1561\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1561\"><p>Se a garrafa t\u00e9rmica for feita de a\u00e7o inoxid\u00e1vel de alta qualidade, como a nossa, proteger sua sa\u00fade \u00e9 o benef\u00edcio n\u00famero um. Por qu\u00ea? As garrafas de pl\u00e1stico s\u00e3o feitas de tereftalato de polietileno. Parece assustador e \u00e9. O que acontece quando esse material entra em contato com a \u00e1gua quente \u00e9 que ele libetra o bisfenol A qu\u00edmico, mais conhecido como BPA. Este composto \u00e9 prejudicial ao organismo, pois leva a uma variedade de problemas, incluindo tonturas, depress\u00e3o, n\u00e1usea e outros efeitos. Portanto, evite o pl\u00e1stico e seu corpo agradecer\u00e1.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1562\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-1562\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Ajudamos a natureza mudando para garrafas t\u00e9rmicas reutiliz\u00e1veis?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1562\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1562\"><p>Ao escolher as garrafas t\u00e9rmicas de uso m\u00faltiplo em vez de pl\u00e1stico, est\u00e1 a mostrar que se preocupa com o meio ambiente e o quer ajudar de qualquer maneira. Estrela de ouro para si! Sabia que as empresas deo meio usam milh\u00f5es de barris de petr\u00f3leo todos os anos para criar garrafas de pl\u00e1stico? E h\u00e1 mais. Apenas um pequeno n\u00famero de garrafas \u00e9 reciclado ap\u00f3s o uso &#8211; para ser mais preciso, 38 de 167 garrafas descart\u00e1veis. Bil\u00f5es delas v\u00e3o para o lixo todos os anos, poluindo grande volume de aterros e cursos de \u00e1gua. A escolha de garrafas t\u00e9rmicas reutiliz\u00e1veis \u200b\u200bem vez de garrafas pl\u00e1sticas \u00e9 um pequeno passo de grande import\u00e2ncia &#8211; na dire\u00e7\u00e3o de ajudar o meio ambiente<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1563\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-1563\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Quanto tempo a minha garrafa t\u00e9rmica vai durar?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1563\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1563\"><p>Uma garrafa t\u00e9rmica com infusor mantida adequadamente permanecer\u00e1 com o seu brilho ap\u00f3s centenas de lavagens, mantendo o sabor fresco do ch\u00e1 dentro e deixando-a longe de uma quantidade de preocupa\u00e7\u00f5es sobre BPAs e outros produtos qu\u00edmicos t\u00f3xicos associados ao uso de pl\u00e1stico. Al\u00e9m disso, as garrafas t\u00e9rmicas de a\u00e7o inoxid\u00e1vel permanecem impec\u00e1veis \u200b\u200bmesmo ap\u00f3s o uso prolongado, ao contr\u00e1rio das garrafas pl\u00e1sticas que ficam descoloridas e degradam depois de serem usadas apenas algumas vezes.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1564\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-1564\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Como manter a minha garrafa t\u00e9rmica limpa?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1564\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1564\"><p>Para manter sua garrafa t\u00e9rmica no seu melhor, lave-a todos os dias. Basta colocar um pouco de \u00e1gua morna e sab\u00e3o em p\u00f3 na garrafa t\u00e9rmica, agitar e deixar por 5 minutos. Use um pano ou escova no interior para remover qualquer ac\u00famulo viscoso que possa se ter formado. Enx\u00e1gue bem e sua garrafa t\u00e9rmica est\u00e1 pronta para ser usada novamente.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7e3682 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7e3682\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d213663\" data-id=\"d213663\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f723a9 elementor-widget elementor-widget-custom_title\" data-id=\"7f723a9\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>F\u00c1CIL DE PREPARAR<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebef688 elementor-widget elementor-widget-text-editor\" data-id=\"ebef688\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<strong>Voc\u00ea escolhe como.\n<\/strong>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd3888a elementor-section-height-min-height elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"bd3888a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-13f33aa animated-slow elementor-invisible\" data-id=\"13f33aa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;50&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e0635c elementor-widget elementor-widget-heading\" data-id=\"4e0635c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec6678 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9ec6678\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f137a04 elementor-widget elementor-widget-text-editor\" data-id=\"f137a04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>P\u00f5e 7gr (uma colher de sopa) de ch\u00e1 com 400-500ml de \u00e1gua a ferver<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fa9180 elementor-widget elementor-widget-image\" data-id=\"6fa9180\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/nl\/files\/2021\/07\/Preparation-pink-1.jpg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4d8ee3a animated-slow elementor-invisible\" data-id=\"4d8ee3a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;550&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d39563e elementor-widget elementor-widget-heading\" data-id=\"d39563e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb361e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6cb361e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e9835e elementor-widget elementor-widget-text-editor\" data-id=\"4e9835e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Reposar por 7 minutos<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8306054 elementor-widget elementor-widget-image\" data-id=\"8306054\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"500\" height=\"500\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2.jpg\" class=\"attachment-large size-large wp-image-137747\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2.jpg 500w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-45x45.jpg 45w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-70dfed7 animated-slow elementor-invisible\" data-id=\"70dfed7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;1050&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa1e51 elementor-widget elementor-widget-heading\" data-id=\"7fa1e51\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e730c2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1e730c2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-528efa6 elementor-widget elementor-widget-text-editor\" data-id=\"528efa6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Disfruta do sabor<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09cde48 elementor-widget elementor-widget-image\" data-id=\"09cde48\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"500\" height=\"500\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3.jpg\" class=\"attachment-large size-large wp-image-137748\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3.jpg 500w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-45x45.jpg 45w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"|\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-491f433 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"491f433\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5eb18a\" data-id=\"c5eb18a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beb5566 pp-card-slider-dots-bottom pp-card-slider-image-left elementor--star-style-star_fontawesome elementor-widget elementor-widget-pp-card-slider\" data-id=\"beb5566\" data-element_type=\"widget\" data-settings=\"{&quot;date&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;yes&quot;,&quot;pagination_type&quot;:&quot;bullets&quot;,&quot;keyboard_nav&quot;:&quot;no&quot;}\" data-widget_type=\"pp-card-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-card-slider-wrapper\">\n\t\t\t<div class=\"pp-card-slider pp-swiper-slider\" data-slider-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;speed&quot;:&quot;100&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;slidesPerView&quot;:1,&quot;grabCursor&quot;:false,&quot;autoHeight&quot;:false,&quot;loop&quot;:true,&quot;fadeEffect&quot;:{&quot;crossFade&quot;:true},&quot;autoplay&quot;:{&quot;delay&quot;:999999,&quot;disableOnInteraction&quot;:false},&quot;pagination&quot;:{&quot;el&quot;:&quot;.swiper-pagination&quot;,&quot;type&quot;:&quot;bullets&quot;,&quot;clickable&quot;:true}}\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-e83984c\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"beb5566\" data-elementor-lightbox-index=\"0\" href=\"https:\/\/wowtea.eu\/nl\/files\/2021\/07\/Preparation-pink-1.jpg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/nl\/files\/2021\/07\/Preparation-pink-1.jpg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>P\u00f5e 7gr (uma colher de sopa) de ch\u00e1 com 400-500ml de \u00e1gua a ferver<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t1.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-bc28e98\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"beb5566\" data-elementor-lightbox-index=\"1\" href=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2.jpg\" class=\"elementor-clickable\"><img width=\"500\" height=\"500\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2.jpg\" class=\"attachment-large size-large wp-image-137747\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2.jpg 500w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-2-45x45.jpg 45w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"|\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>Reposar por 7 minutos<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t2.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-657683b\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"beb5566\" data-elementor-lightbox-index=\"2\" href=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3.jpg\" class=\"elementor-clickable\"><img width=\"500\" height=\"500\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3.jpg\" class=\"attachment-large size-large wp-image-137748\" alt=\"|\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3.jpg 500w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Preparation-pink-3-45x45.jpg 45w\" sizes=\"(max-width: 500px) 100vw, 500px\" title=\"|\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>Disfruta do sabor<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t3.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<!-- Add Arrows -->\n\t\t\t<!-- <div class=\"swiper-button-prev swiper-button-prev-<?\/\/php echo esc_attr( $this->get_id() ); ?>\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"<?\/\/php echo esc_attr( $prev_arrow ); ?>\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-button-next swiper-button-next-<?\/\/php echo esc_attr( $this->get_id() ); ?>\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"<?\/\/php echo esc_attr( $next_arrow ); ?>\"><\/i>\n\t\t\t\t<\/div> -->\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b73a071 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b73a071\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c4569e\" data-id=\"2c4569e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45e89bb elementor-widget elementor-widget-custom_title\" data-id=\"45e89bb\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>\u041a\u0410\u041a\u0412\u041e \u041a\u0410\u0417\u0412\u0410\u0422 \u0417\u0410 <br>\u041f\u0420\u041e\u0414\u0423\u041a\u0422\u0410<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ce7e75 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ce7e75\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0daaa5c box\" data-id=\"0daaa5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d8dc11 pp-card-slider-dots-bottom pp-card-slider-image-left elementor--star-style-star_fontawesome elementor-widget elementor-widget-pp-card-slider\" data-id=\"8d8dc11\" data-element_type=\"widget\" data-settings=\"{&quot;keyboard_nav&quot;:&quot;yes&quot;,&quot;grab_cursor&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:&quot;9000&quot;,&quot;date&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;yes&quot;,&quot;pagination_type&quot;:&quot;bullets&quot;}\" data-widget_type=\"pp-card-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-card-slider-wrapper\">\n\t\t\t<div class=\"pp-card-slider pp-swiper-slider\" data-slider-settings=\"{&quot;direction&quot;:&quot;horizontal&quot;,&quot;speed&quot;:&quot;100&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;slidesPerView&quot;:1,&quot;grabCursor&quot;:true,&quot;autoHeight&quot;:false,&quot;loop&quot;:true,&quot;fadeEffect&quot;:{&quot;crossFade&quot;:true},&quot;autoplay&quot;:{&quot;delay&quot;:&quot;9000&quot;,&quot;disableOnInteraction&quot;:true},&quot;keyboard&quot;:{&quot;enabled&quot;:true},&quot;pagination&quot;:{&quot;el&quot;:&quot;.swiper-pagination&quot;,&quot;type&quot;:&quot;bullets&quot;,&quot;clickable&quot;:true}}\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-0ac32ce\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d8dc11\" data-elementor-lightbox-index=\"0\" href=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/204269901_970100420471202_6536845224073196906_n.jpg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/204269901_970100420471202_6536845224073196906_n.jpg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>\u041e\u0431\u0438\u0447\u0430\u043c \u0434\u0430 \u043a\u043e\u043c\u0431\u0438\u043d\u0438\u0440\u0430\u043c SlimFit SuperFood \u0441 \u043f\u043e\u0447\u0442\u0438 \u0432\u0441\u0438\u0447\u043a\u043e! \u041b\u044e\u0431\u0438\u043c\u0430\u0442\u0430 \u043c\u0438 \u0440\u0435\u0446\u0435\u043f\u0442\u0430 \u0432\u0441\u0435 \u043f\u0430\u043a \u0435 \u0441 \u043a\u0438\u0441\u0435\u043b\u043e \u043c\u043b\u044f\u043a\u043e! \u0412\u043a\u0443\u0441\u043d\u043e! \u0414\u043e\u043f\u0430\u0434\u0430 \u043c\u0438, \u0447\u0435 \u0438\u043c\u0430 \u0432\u0441\u0438\u0447\u043a\u0438 \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u043d\u0438 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0438, \u0432\u043a\u043b\u044e\u0447\u0435\u043d\u0438 \u0432 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430. \u0422\u043e\u0437\u0438 \u043c\u0438\u043a\u0441 \u043c\u0435 \u0434\u044a\u0440\u0436\u0438 \u043f\u044a\u043b\u043d\u043e\u0446\u0435\u043d\u043d\u043e \u043d\u0430\u0445\u0440\u0430\u043d\u0435\u043d\u0430 \u0441\u0443\u0442\u0440\u0438\u043d, \u0430 \u0433\u043b\u0430\u0434\u0430 \u043c\u0438 \u0437\u0430 \u0437\u0430\u0445\u0430\u0440 \u043d\u0430\u043c\u0430\u043b\u044f.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t\u0412\u0435\u0440\u043e\u043d\u0438\u043a\u0430 \u0422.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\tVerified Customer\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-5\">&#61445;<\/i><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-baf8450\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d8dc11\" data-elementor-lightbox-index=\"1\" href=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/IMG_20200528_143839_714.jpg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/IMG_20200528_143839_714.jpg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>\u041e\u0442 5-\u0434\u0435\u043d\u0430 \u0441\u044a\u043c \u043d\u0430 Slimfit Superfood. \u041f\u0440\u0438\u0433\u043e\u0442\u0432\u044f\u043c \u0433\u043e \u043a\u0430\u0442\u043e \u0441\u043c\u0443\u0442\u0438 \u0437\u0430 \u0437\u0430\u043a\u0443\u0441\u043a\u0430 \u0441 \u0433\u043e\u0440\u0441\u043a\u0438 \u043f\u043b\u043e\u0434\u043e\u0432\u0435 \u0438 \u043a\u0438\u0441\u0435\u043b\u043e \u043c\u043b\u044f\u043a\u043e. \u041e\u0442 \u0441\u0443\u0442\u0440\u0438\u043d\u0442\u0430 \u043c\u0435 \u0441\u0438\u0442\u0430. \u0412\u043a\u043b\u044e\u0447\u0432\u0430\u043c \u043b\u044e\u0431\u0438\u043c\u0438\u0442\u0435 \u0441\u0438 \u043f\u043b\u043e\u0434\u043e\u0432\u0435 \u0438 \u0437\u0435\u043b\u0435\u043d\u0447\u0443\u0446\u0438, \u0437\u0430 \u0434\u0430 \u043d\u0430\u043f\u0440\u0430\u0432\u044f \u0432\u043a\u0443\u0441\u0435\u043d \u0448\u0435\u0439\u043a. \u041e\u0431\u0438\u0447\u0430\u043c \u0434\u0430 \u0434\u043e\u0431\u0430\u0432\u044f\u0442\u0435 \u0446\u0432\u0435\u043a\u043b\u043e \u0437\u0430 \u043e\u0441\u0432\u0435\u0436\u0430\u0432\u0430\u0449\u043e \u0441\u043c\u0443\u0442\u0438.\u041f\u0440\u0435\u043f\u043e\u0440\u044a\u0447\u0430\u043c \u0434\u0430 \u0433\u043e \u0445\u0430\u043f\u0432\u0430\u0442\u0435 \u043a\u0440\u0430\u0439 \u0431\u0430\u0441\u0435\u0439\u043d\u0430, \u0437\u0430 \u0434\u0430 \u0437\u0430\u043f\u043e\u0447\u043d\u0435\u0442\u0435 \u043f\u043e\u0447\u0438\u0432\u043d\u0438\u044f \u0441\u0438 \u0434\u0435\u043d \u0441 \u0443\u0441\u043c\u0438\u0432\u043a\u0430! \ud83d\ude42<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t\u0413\u0435\u0440\u0433\u0430\u043d\u0430 \u0412.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\tVerified Customer\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-8c4a9e6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d8dc11\" data-elementor-lightbox-index=\"2\" href=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/image2-3.jpeg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/image2-3.jpeg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>\u041d\u0438\u043a\u043e\u0433\u0430 \u043d\u0435 \u0441\u044a\u043c \u0441\u0435 \u0447\u0443\u0432\u0441\u0442\u0432\u0430\u043b\u0430 \u043f\u043e-\u0434\u043e\u0431\u0440\u0435, \u0430 SlimFit Super Food \u043c\u0438 \u043f\u043e\u043c\u0430\u0433\u0430 \u0434\u0430 \u043e\u0442\u043a\u0440\u0438\u044f \u0434\u0438\u0435\u0442\u0430 \u043d\u0430 \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u0430 \u043e\u0441\u043d\u043e\u0432\u0430, \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0432\u0438 \u0437\u0430 \u0441\u044a\u0437\u0434\u0430\u0432\u0430\u043d\u0435\u0442\u043e \u043d\u0430 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0438, \u043a\u043e\u0438\u0442\u043e \u0438\u043c\u0430\u0442 \u0434\u043e\u0431\u044a\u0440 \u0432\u043a\u0443\u0441 \u0438\u0438\u043c\u0430\u0442 \u0441\u044a\u0441\u0442\u0430\u0432\u043a\u0438 \u0441\u044a\u0431\u0440\u0430\u043d\u0438 \u043e\u0442 \u043d\u0430\u0439-\u0434\u043e\u0431\u0440\u0438\u0442\u0435 \u043c\u0435\u0441\u0442\u0430. \u041f\u0440\u0438\u0433\u043e\u0442\u0432\u044f\u043d\u0435\u0442\u043e \u043c\u0443 \u0441 \u044f\u0433\u043e\u0434\u043e\u0432 \u0448\u0435\u0439\u043a \u0431\u0435\u0448\u0435 \u0447\u0443\u0434\u0435\u0441\u043d\u0430 \u0438\u0437\u043d\u0435\u043d\u0430\u0434\u0430 \u0438 \u043c\u043d\u043e\u0433\u043e \u0432\u043a\u0443\u0441\u043d\u0430.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t\u041c\u0438\u0445\u0430\u0435\u043b\u0430 \u0418.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\tVerified Customer\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-5\">&#61445;<\/i><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-b00211d\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d8dc11\" data-elementor-lightbox-index=\"3\" href=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/117759451_126027245527579_5024993932048068515_n.jpg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/117759451_126027245527579_5024993932048068515_n.jpg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>\u0417\u0430 3 \u0434\u043d\u0438 \u043f\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u0430\u0445 \u0440\u0430\u0437\u043b\u0438\u043a\u0430! \u0411\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0432\u0438, \u0447\u0435 \u0441\u044a\u0437\u0434\u0430\u0434\u043e\u0445\u0442\u0435 \u0442\u0430\u043a\u044a\u0432 \u0432\u0438\u0441\u043e\u043a\u043e\u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d \u043f\u0440\u043e\u0434\u0443\u043a\u0442! \u0410\u0437 \u0441\u044a\u043c \u043f\u043e\u0441\u0432\u0435\u0442\u0435\u043d\u0430 \u043d\u0430 \u0434\u043e\u0432\u044a\u0440\u0448\u0432\u0430\u043d\u0435\u0442\u043e \u043d\u0430 \u0446\u044f\u043b\u0430\u0442\u0430 \u043e\u043f\u0430\u043a\u043e\u0432\u043a\u0430 \u0441\u0435\u0433\u0430.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t\u041a\u0440\u0430\u0441\u0438\u043c\u0438\u0440\u0430 \u0421.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\tVerified Customer\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-5\">&#61445;<\/i><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-card-slider-item swiper-slide elementor-repeater-item-cba21ad\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-image\">\n\t\t\t\t\t\t<a data-elementor-open-lightbox=\"default\" data-elementor-lightbox-slideshow=\"8d8dc11\" data-elementor-lightbox-index=\"4\" href=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/k.a.z.a.k.o.v.a.jpeg\" class=\"elementor-clickable\"><img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/06\/k.a.z.a.k.o.v.a.jpeg\" title=\"|\" alt=\"|\" loading=\"lazy\"><\/a>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-content\">\n\t\t\t\t\t\t\t<p>\u041f\u043e\u0437\u043d\u0430\u0432\u0430\u043d\u0435\u0442\u043e \u043d\u0430 \u0441\u044a\u0441\u0442\u0430\u0432\u043a\u0438\u0442\u0435 \u0435 \u043f\u043e\u043b\u0435\u0437\u043d\u043e \u0437\u0430 \u0432\u0441\u0435\u043a\u0438 \u0438 \u0447\u0435 \u0432\u043a\u0443\u0441\u044a\u0442 \u0435 \u043f\u0440\u0435\u043a\u0440\u0430\u0441\u0435\u043d, \u043f\u0440\u0438\u0433\u043e\u0442\u0432\u0435\u043d \u0432 \u0448\u0435\u0439\u043a\u043e\u0432\u0435 \u0438\u043b\u0438 \u043a\u0438\u0441\u0435\u043b\u043e \u043c\u043b\u044f\u043a\u043e \u0438\u043b\u0438 \u0442\u0435\u0447\u043d\u043e\u0441\u0442\u0438 \u0433\u043e \u043f\u0440\u0430\u0432\u0438 \u043f\u043e\u0431\u0435\u0434\u0438\u0442\u0435\u043b \u0432 \u043c\u043e\u0435\u0442\u043e \u0434\u043e\u043c\u0430\u043a\u0438\u043d\u0441\u0442\u0432\u043e.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"pp-card-slider-title\">\n\t\t\t\t\t\t\t\u0419\u043e\u0430\u043d\u0430 \u0412.\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-card-slider-date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-check\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-card-slider-meta-text\">\n\t\t\t\t\t\t\t\tVerified Customer\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-star-rating\"><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-full\">&#61445;<\/i><i class=\"elementor-star-5\">&#61445;<\/i><\/div>\t\t\t\t\t\t\n\t\t\t\t\t\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<!-- Add Arrows -->\n\t\t\t<!-- <div class=\"swiper-button-prev swiper-button-prev-<?\/\/php echo esc_attr( $this->get_id() ); ?>\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"<?\/\/php echo esc_attr( $prev_arrow ); ?>\"><\/i>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-button-next swiper-button-next-<?\/\/php echo esc_attr( $this->get_id() ); ?>\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"<?\/\/php echo esc_attr( $next_arrow ); ?>\"><\/i>\n\t\t\t\t<\/div> -->\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c76ae17 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c76ae17\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43693ee\" data-id=\"43693ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-765283e elementor-widget elementor-widget-custom_title\" data-id=\"765283e\" data-element_type=\"widget\" data-widget_type=\"custom_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t      <!-- border_title center_border -->\n      \n               <div class=\"custom_title\"  >\n            <h2 class=\"title border_title center \"><span>\u0427\u0415\u0421\u0422\u041e \u0417\u0410\u0414\u0410\u0412\u0410\u041d\u0418 \u0412\u042a\u041f\u0420\u041e\u0421\u0418<\/span> <\/h2>\n         <\/div>\n      \n\n   \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa62a92 elementor-hidden-phone elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa62a92\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c4ce0f\" data-id=\"9c4ce0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-047f3ac elementor-widget elementor-widget-pp-advanced-tabs\" data-id=\"047f3ac\" data-element_type=\"widget\" data-widget_type=\"pp-advanced-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-tabs pp-style-custom pp-tabs-responsive-tablet pp-advabced-tabs-responsive\" role=\"tablist\">\n\t\t\t<div class=\"pp-advanced-tabs-wrapper pp-tabs-labels at-horizontal  at-hover\">\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"pp-advanced-tabs-title-4711\" class=\"pp-advanced-tabs-title pp-tabs-label pp-advanced-tabs-desktop-title pp-tab-active\" data-tab=\"1\" data-index=\"4711\" tabindex=\"4711\" role=\"tab\" aria-controls=\"pp-advanced-tabs-content-4711\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041a\u0430\u043a \u0440\u0430\u0431\u043e\u0442\u0438<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"pp-advanced-tabs-title-4712\" class=\"pp-advanced-tabs-title pp-tabs-label pp-advanced-tabs-desktop-title \" data-tab=\"2\" data-index=\"4712\" tabindex=\"4712\" role=\"tab\" aria-controls=\"pp-advanced-tabs-content-4712\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041f\u0440\u0438\u0435\u043c<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"pp-advanced-tabs-title-4713\" class=\"pp-advanced-tabs-title pp-tabs-label pp-advanced-tabs-desktop-title \" data-tab=\"3\" data-index=\"4713\" tabindex=\"4713\" role=\"tab\" aria-controls=\"pp-advanced-tabs-content-4713\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041f\u0440\u0438\u0433\u043e\u0442\u0432\u044f\u043d\u0435<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"pp-advanced-tabs-title-4714\" class=\"pp-advanced-tabs-title pp-tabs-label pp-advanced-tabs-desktop-title \" data-tab=\"4\" data-index=\"4714\" tabindex=\"4714\" role=\"tab\" aria-controls=\"pp-advanced-tabs-content-4714\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pp-advanced-tabs-content-wrapper pp-tabs-panels at-horizontal-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-tabs-panel\">\n\t\t\t\t\t<div class=\"pp-advanced-tabs-title pp-tabs-label pp-tab-responsive pp-tab-active at-hover\" data-index =\"4711\">\n\t\t\t\t\t\t<div class=\"pp-advanced-tabs-title-inner\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041a\u0430\u043a \u0440\u0430\u0431\u043e\u0442\u0438<\/span>\n\t\t\t\t\t\t\t<i class=\"pp-toggle-icon pp-tab-open fa\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"pp-advanced-tabs-content-4711\" class=\"pp-advanced-tabs-content elementor-clearfix pp-advanced-tabs-section pp-tab-active\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-advanced-tabs-title-4711\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-tabs-panel\">\n\t\t\t\t\t<div class=\"pp-advanced-tabs-title pp-tabs-label pp-tab-responsive  at-hover\" data-index =\"4712\">\n\t\t\t\t\t\t<div class=\"pp-advanced-tabs-title-inner\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041f\u0440\u0438\u0435\u043c<\/span>\n\t\t\t\t\t\t\t<i class=\"pp-toggle-icon pp-tab-open fa\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"pp-advanced-tabs-content-4712\" class=\"pp-advanced-tabs-content elementor-clearfix pp-advanced-tabs-section \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"pp-advanced-tabs-title-4712\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-tabs-panel\">\n\t\t\t\t\t<div class=\"pp-advanced-tabs-title pp-tabs-label pp-tab-responsive  at-hover\" data-index =\"4713\">\n\t\t\t\t\t\t<div class=\"pp-advanced-tabs-title-inner\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041f\u0440\u0438\u0433\u043e\u0442\u0432\u044f\u043d\u0435<\/span>\n\t\t\t\t\t\t\t<i class=\"pp-toggle-icon pp-tab-open fa\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"pp-advanced-tabs-content-4713\" class=\"pp-advanced-tabs-content elementor-clearfix pp-advanced-tabs-section \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"pp-advanced-tabs-title-4713\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-tabs-panel\">\n\t\t\t\t\t<div class=\"pp-advanced-tabs-title pp-tabs-label pp-tab-responsive  at-hover\" data-index =\"4714\">\n\t\t\t\t\t\t<div class=\"pp-advanced-tabs-title-inner\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon pp-advanced-tabs-icon-left\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"pp-advanced-tabs-title-text\">\u041a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e<\/span>\n\t\t\t\t\t\t\t<i class=\"pp-toggle-icon pp-tab-open fa\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"pp-advanced-tabs-content-4714\" class=\"pp-advanced-tabs-content elementor-clearfix pp-advanced-tabs-section \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"pp-advanced-tabs-title-4714\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7042700 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7042700\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddcaa3b\" data-id=\"ddcaa3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c5ee24 elementor-widget elementor-widget-pp-advanced-accordion\" data-id=\"8c5ee24\" data-element_type=\"widget\" data-settings=\"{&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-advanced-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-8c5ee24\" data-accordion-id=\"8c5ee24\">\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t<div id=\"pp-accordion-tab-title-1471\" class=\"pp-accordion-tab-title\" tabindex=\"1471\" data-tab=\"1\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1471\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-tab-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\t\u041a\u0430\u043a \u0440\u0430\u0431\u043e\u0442\u0438\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1471\" class=\"pp-accordion-tab-content\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1471\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t<div id=\"pp-accordion-tab-title-1472\" class=\"pp-accordion-tab-title\" tabindex=\"1472\" data-tab=\"2\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1472\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\t\u041f\u0440\u0438\u0435\u043c\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1472\" class=\"pp-accordion-tab-content\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1472\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t<div id=\"pp-accordion-tab-title-1473\" class=\"pp-accordion-tab-title\" tabindex=\"1473\" data-tab=\"3\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1473\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\t\u041f\u0440\u0438\u0433\u043e\u0442\u0432\u044f\u043d\u0435\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1473\" class=\"pp-accordion-tab-content\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1473\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-accordion-item\">\n\t\t\t\t\t<div id=\"pp-accordion-tab-title-1474\" class=\"pp-accordion-tab-title\" tabindex=\"1474\" data-tab=\"4\" role=\"tab\" aria-controls=\"pp-accordion-tab-content-1474\">\n\t\t\t\t\t\t<span class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\t\u041a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"pp-accordion-tab-content-1474\" class=\"pp-accordion-tab-content\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"pp-accordion-tab-title-1474\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ed6e39 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6ed6e39\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9d0718\" data-id=\"b9d0718\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9dc44f elementor-widget elementor-widget-template\" data-id=\"a9dc44f\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"187194\" class=\"elementor elementor-187194\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25262be elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25262be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-129f5b0\" data-id=\"129f5b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd6b2d1 elementor-widget elementor-widget-text-editor\" data-id=\"bd6b2d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Se voc\u00ea tiver alguma d\u00favida, n\u00e3o hesite em nos contatar.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e23eb49 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"e23eb49\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-shrink elementor-repeater-item-fd8c06f\" href=\"https:\/\/www.facebook.com\/wowteaportugal\/\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-shrink elementor-repeater-item-d0e60b6\" href=\"https:\/\/www.instagram.com\/wowteaportuguese\/\" target=\"_blank\" rel=\"nofollow noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-envelope elementor-animation-shrink elementor-repeater-item-d35abff\" href=\"https:\/\/wowtea.eu\/pt\/contact\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Envelope<\/span>\n\t\t\t\t\t\t<i class=\"fas fa-envelope\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2babb4e\" data-id=\"2babb4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e0b690 elementor-widget elementor-widget-image\" data-id=\"4e0b690\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/wowtea.eu\/wp-content\/uploads\/2021\/04\/wowtea-logo-1.svg\" title=\"|\" alt=\"|\" loading=\"lazy\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1842e9a elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"1842e9a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cd0455\" data-id=\"6cd0455\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d18a5b4 elementor-widget elementor-widget-spacer\" data-id=\"d18a5b4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fea6408 elementor-widget elementor-widget-heading\" data-id=\"fea6408\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> <span style=\"font-weight:600\">Pare de fazer scroll.<br>Comece a mudan\u00e7a.<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a69fc1 elementor-section-height-min-height elementor-hidden-phone elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"9a69fc1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e44b17\" data-id=\"4e44b17\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-395aebd elementor-widget elementor-widget-spacer\" data-id=\"395aebd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00d49ce elementor-widget elementor-widget-heading\" data-id=\"00d49ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> <span style=\"font-weight:600\">Pare de fazer scroll. Comece a mudan\u00e7a.<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47c3737 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"47c3737\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c3d0b5\" data-id=\"6c3d0b5\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a02d691 elementor-widget elementor-widget-template\" data-id=\"a02d691\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"185276\" class=\"elementor elementor-185276\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29219e2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29219e2a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d894876\" data-id=\"1d894876\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a8ccb92 elementor-widget elementor-widget-html\" data-id=\"4a8ccb92\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- TrustBox widget - Carousel -->\r\n<div class=\"trustpilot-widget\" data-locale=\"pt-PT\" data-template-id=\"53aa8912dec7e10d38f59f36\" data-businessunit-id=\"60029def312cb900013df992\" data-style-height=\"320px\" data-style-width=\"100%\" data-theme=\"light\" data-tags=\"PT\" data-stars=\"1,2,3,4,5\">\r\n  <a href=\"https:\/\/pt.trustpilot.com\/review\/wowtea.eu\" target=\"_blank\" rel=\"noopener\">Trustpilot<\/a>\r\n<\/div>\r\n<!-- End TrustBox widget -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p><strong>500 ml<\/strong><\/p>\n<p>Termo para ch\u00e1 rosa \u2013 luxuoso e leve \u2013 concebido para si e para aqueles momentos em que deseja andar com algo bonito, pr\u00e1tico e sustent\u00e1vel.<br \/>\nFabricado em a\u00e7o inoxid\u00e1vel de alta qualidade.<br \/>\nEscolha o rosa \u2013 para momentos de ch\u00e1 alegres e elegantes!<\/p>\n","protected":false},"featured_media":156043,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"product_cat":[338,455,148,330],"product_tag":[],"acf":[],"variations_data":{"109219":{"id":109219,"name":"Garrafa t\u00e9rmica rosa com infusor","slug":"garrafa-termica-rosa-com-infusor","date_created":{"date":"2021-07-14 14:58:27.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"date_modified":{"date":"2025-11-30 23:31:32.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"status":"publish","featured":false,"catalog_visibility":"visible","description":"O termo de infus\u00e3o perfeito","short_description":"","sku":"WOW-T-TTP","price":"28.6","regular_price":"28.6","sale_price":"","date_on_sale_from":null,"date_on_sale_to":null,"total_sales":"0","tax_status":"taxable","tax_class":"parent","manage_stock":false,"stock_quantity":null,"stock_status":"instock","backorders":"no","low_stock_amount":"","sold_individually":false,"weight":"","length":"","width":"","height":"","upsell_ids":[],"cross_sell_ids":["190921","190917","190805","190857","190913","190789","190746","190741","190738","190732","190862","190919","190916","190804","190855","190911","190787"],"parent_id":109212,"reviews_allowed":false,"purchase_note":"","attributes":{"pa_thermos-upsell":"garrafa-termica-rosa-com-infusor"},"default_attributes":[],"menu_order":1,"post_password":"","virtual":false,"downloadable":false,"category_ids":[],"tag_ids":[],"shipping_class_id":0,"downloads":[],"image_id":156043,"gallery_image_ids":[],"download_limit":-1,"download_expiry":-1,"rating_counts":[],"average_rating":0,"review_count":0,"attribute_summary":"Thermos upsell: Garrafa t\u00e9rmica rosa com infusor","meta_data":[{"id":1039717,"key":"yst_prominent_words_version","value":"1"},{"id":1039796,"key":"_gtin","value":""},{"id":1039797,"key":"_variable_text_field_1","value":"WOW TEA Garrafa T\u00e9rmica para ch\u00e1 com filtro - 500ml - Rosa"},{"id":1039798,"key":"_variable_text_field_2","value":"Garrafa t\u00e9rmica com infusor - Materiais de alta qualidade. Feito com a\u00e7o inoxid\u00e1vel de qualidade premium, 100% \u00e0 prova de vazamentos e extra dur\u00e1vel \/ durando anos."},{"id":1039799,"key":"_variable_text_field_3","value":""},{"id":1039800,"key":"fstr-p-sub","value":""},{"id":1898297,"key":"_sold_variation_individually","value":"no"},{"id":1898298,"key":"_v_label_field","value":"regular_price"},{"id":2667859,"key":"oms_price_updated_at","value":"2025-12-01 01:34:27"},{"id":2667861,"key":"_old_regular_price","value":"28.6"},{"id":2667862,"key":"_old_sale_price","value":"25.7"},{"id":2955766,"key":"_custom_variation_title","value":"Termo de infus\u00e3o de ch\u00e1 \u2013 Rosa"}],"price_html":"<span class=\"woocommerce-Price-amount amount\"><bdi>28,60&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span>","image":"<img width=\"600\" height=\"600\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-600x600.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image.png 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-300x300.png 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-150x150.png 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-100x100.png 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-60x60.png 60w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-90x90.png 90w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image-45x45.png 45w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>","free_delivery":false},"109221":{"id":109221,"name":"Detox + Garrafa t\u00e9rmica rosa com infusor","slug":"spring-reborn-11","date_created":{"date":"2021-07-14 14:58:27.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"date_modified":{"date":"2025-12-01 07:33:31.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"status":"publish","featured":false,"catalog_visibility":"visible","description":"Detox + Garrafa T\u00e9rmica Rosa","short_description":"","sku":"WOW-P-DTXTTP","price":"47.30","regular_price":"52.5","sale_price":"47.30","date_on_sale_from":null,"date_on_sale_to":null,"total_sales":"0","tax_status":"taxable","tax_class":"parent","manage_stock":false,"stock_quantity":null,"stock_status":"instock","backorders":"no","low_stock_amount":"","sold_individually":false,"weight":"","length":"","width":"","height":"","upsell_ids":[],"cross_sell_ids":["190921","190917","190805","190857","190913","190789","190746","190741","190738","190732","190862","190919","190916","190804","190855","190911","190787"],"parent_id":109212,"reviews_allowed":false,"purchase_note":"","attributes":{"pa_thermos-upsell":"detox-pink-thermos"},"default_attributes":[],"menu_order":2,"post_password":"","virtual":false,"downloadable":false,"category_ids":[],"tag_ids":[],"shipping_class_id":0,"downloads":[],"image_id":156037,"gallery_image_ids":[],"download_limit":-1,"download_expiry":-1,"rating_counts":[],"average_rating":0,"review_count":0,"attribute_summary":"Thermos upsell: Detox + Garrafa t\u00e9rmica rosa com infusor","meta_data":[{"id":1039817,"key":"_gtin","value":""},{"id":1039818,"key":"_variable_text_field_1","value":""},{"id":1039819,"key":"_variable_text_field_2","value":""},{"id":1039820,"key":"_variable_text_field_3","value":""},{"id":1039821,"key":"fstr-p-sub","value":""},{"id":2393533,"key":"_sold_variation_individually","value":"no"},{"id":2393534,"key":"_v_label_field","value":""},{"id":2668196,"key":"oms_price_updated_at","value":"2025-12-01 09:33:29"},{"id":2668197,"key":"_old_regular_price","value":"52.5"},{"id":2668198,"key":"_old_sale_price","value":"39.4"},{"id":2858435,"key":"_label_field","value":"Save 15%"},{"id":2955767,"key":"_custom_variation_title","value":"Active Detox Infusion"}],"price_html":"<del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>52,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <ins><span class=\"woocommerce-Price-amount amount\"><bdi>47,30&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins>","image":"<img width=\"600\" height=\"600\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-600x600.jpg 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-1024x1024.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-768x768.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-45x45.jpg 45w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-60x60.jpg 60w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos-90x90.jpg 90w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-detoxpink-thermos.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>","free_delivery":"Entrega gr\u00e1tis"},"109222":{"id":109222,"name":"SlimFit + Garrafa t\u00e9rmica rosa com infusor","slug":"spring-reborn-12","date_created":{"date":"2021-07-14 14:58:27.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"date_modified":{"date":"2025-12-01 07:33:36.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"status":"publish","featured":false,"catalog_visibility":"visible","description":"Slimfit + Garrafa T\u00e9rmica Rosa","short_description":"","sku":"WOW-P-SFTTP","price":"47.30","regular_price":"52.5","sale_price":"47.30","date_on_sale_from":null,"date_on_sale_to":null,"total_sales":"0","tax_status":"taxable","tax_class":"parent","manage_stock":false,"stock_quantity":null,"stock_status":"instock","backorders":"no","low_stock_amount":"","sold_individually":false,"weight":"","length":"","width":"","height":"","upsell_ids":[],"cross_sell_ids":["190921","190917","190805","190857","190913","190789","190746","190741","190738","190732","190862","190919","190916","190804","190855","190911","190787"],"parent_id":109212,"reviews_allowed":false,"purchase_note":"","attributes":{"pa_thermos-upsell":"slimfit-pink-thermos"},"default_attributes":[],"menu_order":3,"post_password":"","virtual":false,"downloadable":false,"category_ids":[],"tag_ids":[],"shipping_class_id":0,"downloads":[],"image_id":156040,"gallery_image_ids":[],"download_limit":-1,"download_expiry":-1,"rating_counts":[],"average_rating":0,"review_count":0,"attribute_summary":"Thermos upsell: SlimFit + Garrafa t\u00e9rmica rosa com infusor","meta_data":[{"id":1039827,"key":"_gtin","value":""},{"id":1039828,"key":"_variable_text_field_1","value":""},{"id":1039829,"key":"_variable_text_field_2","value":""},{"id":1039830,"key":"_variable_text_field_3","value":""},{"id":1039831,"key":"fstr-p-sub","value":""},{"id":2393535,"key":"_sold_variation_individually","value":"no"},{"id":2393536,"key":"_v_label_field","value":""},{"id":2668224,"key":"oms_price_updated_at","value":"2025-12-01 09:49:29"},{"id":2668225,"key":"_old_regular_price","value":"52.5"},{"id":2668226,"key":"_old_sale_price","value":"39.4"},{"id":2955768,"key":"_custom_variation_title","value":"Active Slimfit Infusion"}],"price_html":"<del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>52,50&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <ins><span class=\"woocommerce-Price-amount amount\"><bdi>47,30&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins>","image":"<img width=\"600\" height=\"600\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-600x600.jpg 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-1024x1024.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-768x768.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-45x45.jpg 45w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-60x60.jpg 60w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos-90x90.jpg 90w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-slimpink-thermos.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>","free_delivery":"Entrega gr\u00e1tis"},"109220":{"id":109220,"name":"LOVE YOUR BODY BOX","slug":"love-your-body-box-6","date_created":{"date":"2021-07-14 14:58:27.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"date_modified":{"date":"2026-03-24 02:19:58.000000","timezone_type":3,"timezone":"Europe\/Lisbon"},"status":"publish","featured":false,"catalog_visibility":"visible","description":"Detox + Slimfit + Garrafa T\u00e9rmica Rosa","short_description":"","sku":"WOW-P-SFDTXTTP","price":"64.90","regular_price":"76.4","sale_price":"64.90","date_on_sale_from":null,"date_on_sale_to":null,"total_sales":"0","tax_status":"taxable","tax_class":"parent","manage_stock":false,"stock_quantity":null,"stock_status":"instock","backorders":"no","low_stock_amount":"","sold_individually":false,"weight":"","length":"","width":"","height":"","upsell_ids":[],"cross_sell_ids":["190921","190917","190805","190857","190913","190789","190746","190741","190738","190732","190862","190919","190916","190804","190855","190911","190787"],"parent_id":109212,"reviews_allowed":false,"purchase_note":"","attributes":{"pa_thermos-upsell":"love-your-body-box"},"default_attributes":[],"menu_order":4,"post_password":"","virtual":false,"downloadable":false,"category_ids":[],"tag_ids":[],"shipping_class_id":0,"downloads":[],"image_id":156024,"gallery_image_ids":[],"download_limit":-1,"download_expiry":-1,"rating_counts":[],"average_rating":0,"review_count":0,"attribute_summary":"Thermos upsell: LOVE YOUR BODY BOX","meta_data":[{"id":1039801,"key":"yst_prominent_words_version","value":"1"},{"id":1039807,"key":"_gtin","value":""},{"id":1039808,"key":"_variable_text_field_1","value":""},{"id":1039809,"key":"_variable_text_field_2","value":""},{"id":1039810,"key":"_variable_text_field_3","value":""},{"id":1039811,"key":"fstr-p-sub","value":""},{"id":2393537,"key":"_sold_variation_individually","value":"no"},{"id":2393538,"key":"_v_label_field","value":""},{"id":2668337,"key":"oms_price_updated_at","value":"2026-03-24 04:42:16"},{"id":2668338,"key":"_old_regular_price","value":"76.4"},{"id":2668339,"key":"_old_sale_price","value":"53.5"},{"id":2955769,"key":"_custom_variation_title","value":"Active Infusion Set"}],"price_html":"<del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>76,40&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <ins><span class=\"woocommerce-Price-amount amount\"><bdi>64,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins>","image":"<img width=\"600\" height=\"600\" src=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-600x600.jpg 600w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-300x300.jpg 300w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-1024x1024.jpg 1024w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-150x150.jpg 150w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-768x768.jpg 768w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-100x100.jpg 100w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-45x45.jpg 45w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-60x60.jpg 60w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos-90x90.jpg 90w, https:\/\/wowtea.eu\/pt\/files\/2021\/07\/Biofit-Active-Box-Detox-Slim-PinkThermos.jpg 1080w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>","free_delivery":"Entrega gr\u00e1tis"}},"free_delivery":false,"currency_name":"&euro;","regular_price":"","sale_price":"","price":"28.6","image":"https:\/\/wowtea.eu\/pt\/files\/2021\/07\/wow-tea-Thermos-pink-product-image.png","_links":{"self":[{"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product\/109212"}],"collection":[{"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/comments?post=109212"}],"version-history":[{"count":70,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product\/109212\/revisions"}],"predecessor-version":[{"id":190122,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product\/109212\/revisions\/190122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/media\/156043"}],"wp:attachment":[{"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/media?parent=109212"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product_cat?post=109212"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wowtea.eu\/pt\/wp-json\/wp\/v2\/product_tag?post=109212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}